{"id":1771,"date":"2017-03-20T19:15:46","date_gmt":"2017-03-20T18:15:46","guid":{"rendered":"https:\/\/www.uwg-kreisolpe.de\/site\/?p=1771"},"modified":"2020-01-11T19:20:44","modified_gmt":"2020-01-11T18:20:44","slug":"haushaltsrede-2017","status":"publish","type":"post","link":"https:\/\/www.uwg-kreisolpe.de\/site\/haushaltsrede-2017\/","title":{"rendered":"Haushaltsrede 2017"},"content":{"rendered":"<p><strong>Haushaltsrede 2017<\/strong><br \/>\n<strong>Meinolf Schmidt<\/strong><br \/>\n<strong>Fraktionsvorsitzender der UWG-Fraktion im Kreistag Olpe<\/strong><\/p>\n<p>\u2013 Es gilt das gesprochene Wort \u2013<\/p>\n<p>Sehr geehrter Landrat Beckehoff,<br \/>\nsehr geehrte Mitglieder des Kreistages,<br \/>\nsehr geehrte Damen und Herren,<\/p>\n<p>jedes Jahr wiederholt sich das gleiche Prozedere : Die St\u00e4dte und Gemeinden des Kreises Olpe sehen im Entwurf der Haushaltssatzung eine besorgniserregende Entwicklung.<br \/>\nDer Kreis selbst ger\u00e4t zwischen die R\u00e4der der Kommunen auf der einen Seite und der ebenfalls umlagefinanzierten Landschaftsumlage auf der anderen Seite. Die Ursachen hierf\u00fcr sind nicht neu und liegen offenkundig beim Bund und dem Land NRW. Diese lasten der kommunalen Familie nach wie vor zus\u00e4tzliche teure Aufgaben auf, ohne ausreichende Mittel hierf\u00fcr zur Verf\u00fcgung zu stellen.<\/p>\n<p>90 Prozent des Landschaftshaushaltes, also \u00fcber 3 Milliarden Euro, flie\u00dfen alleine in soziale Leistungen. Die zu erwartende Entwicklung der Landschaftsumlage in den n\u00e4chsten Jahren, deren Ursachen bereits in der Haushaltsrede unseres Landrates ausf\u00fchrlich erl\u00e4utert wurden, lassen auch keine Hoffnung auf eine sinkende Umlage des Landschaftsverbandes Westfalen zu. Interessant hierbei ist jedoch, dass im Vergleich der Landschaftsverband Rheinland den Hebesatz gesenkt hat. Ob die st\u00e4rkere Finanzkraft der Kreise und Kommunen im Rheinland oder h\u00f6here und damit teure Standards in Westfalen hierf\u00fcr verantwortlich sind,\u00a0 wurde, so hofft die UWG-Fraktion, Ende Januar im Kreishaus mit den B\u00fcrgermeistern und dem K\u00e4mmerer des Landschaftsverbandes besprochen.<\/p>\n<p>Die Hoffnung, dass sich diese allj\u00e4hrlich wiederkehrende Situation durch neue Koalitions-vertr\u00e4ge, also durch ein Wechsel der politischen Mehrheiten in Berlin und\/oder D\u00fcsseldorf\u00a0 \u00e4ndert, stirbt zuletzt !<\/p>\n<p>Umso wichtiger erscheint es uns, dass der Kreis Olpe alle denkbaren Anstrengungen unternimmt, die Kreisumlagebelastung nicht weiter steigen zu lassen.<\/p>\n<p>So dominieren die Personalaufwendungen neben der Landschaftsumlage und den Sozialaufwendungen unseren Kreishaushalt. Auch wenn immer darauf hingewiesen wird, dass ein Drittel der Stellen im Stellenplan 2017 geb\u00fchren- bzw. drittfinanziert ist, muss die allj\u00e4hrlich wiederkehrende Kritik der Kommunen endlich beachtet werden und der Personaletat auf Optimierungsbedarf untersucht werden. Der von der SPD eingebrachte und soeben abgelehnte Antrag zur Organisationsuntersuchung der Personalbemessung h\u00e4tte hierzu entschieden beitragen k\u00f6nnen.<\/p>\n<p>Auch die von den B\u00fcrgermeistern ge\u00e4u\u00dferte Kritik hinsichtlich der freiwilligen Leistungen des Kreises, wie der Kooperationsvereinbarung mit der Platin Scala sowie den hohen Aufwendungen f\u00fcr das Kreisjubil\u00e4um wird von unserer Fraktion ausdr\u00fccklich geteilt.<\/p>\n<p>Herr Landrat, meine Damen und Herren !<\/p>\n<p>Ich greife das Stichwort \u201ePlatin Scala\u201c auf und m\u00f6chte das mit dem Wort des Jahres \u201e<strong>Postfaktisch<\/strong>\u201c erg\u00e4nzen.<\/p>\n<p><strong>Postfaktisch<\/strong>, das Wort des Jahres 2016 verweist darauf, dass die Emotionen eine immer gr\u00f6\u00dfere Rolle, auch in den politischen Diskussionen und Entscheidungen spielen und die Fakten und die Wahrheit eine immer geringere Bedeutung haben. Einfach ausgedr\u00fcckt : \u201e<strong>Tatsachen spielen keine Rolle mehr<\/strong>\u201c. Ein Beispiel aus der Kreispolitik ist die Vorlage 219\/2016, besser bekannt unter der \u201eKooperationsvereinbarung mit der Platin Scala\u201c.<\/p>\n<p>So wurde zuerst am 17.11.2016 im Ausschuss f\u00fcr Sport und Kultur die institutionelle F\u00f6rderung in H\u00f6he von 20.000 \u20ac j\u00e4hrlich, bei einer Gegenstimme der UWG, beschlossen.<br \/>\nIn der Sitzung des Kreisausschuss am 21.11.2016 entwickelte sich eine ungew\u00f6hnlich heftige Diskussion zwischen Landrat\/CDU\/SPD einerseits und der UWG\/Gr\u00fcne\/FDP andererseits, die dann am 22.11.2016 mit einer Falschmeldung in der Westfalenpost verk\u00fcndet wurde. Zitat aus der WP : \u201eGestern winkte der Kreisausschuss den Kooperationsvertrag durch, die endg\u00fcltige Zustimmung im Kreistag d\u00fcrfte nur eine Formalie sein\u201c. Nach einer heftigen Protestwelle, nicht nur bei den ehrenamtlich Musiktreibenden, wurden die F\u00f6rderpl\u00e4ne vom Landrat auf einer Pressekonferenz am 30.11.2016 zur\u00fcckgezogen und gl\u00fccklicherweise die Rei\u00dfleine gezogen.<\/p>\n<p>Meine Damen und Herren,<br \/>\nwenn Sie sich jetzt fragen sollten, warum ich diesen Vorgang wieder ausbreite, m\u00f6chte ich Sie an die letzte Kreistagssitzung erinnern, bei der eine gro\u00dfe Mehrheit von CDU und SPD<br \/>\ndie Aufarbeitung und Chance auf Nichtwiederholung durch Absetzung von der Tagesordnung verhindert hat.<\/p>\n<p>Herr Landrat,<br \/>\neine Ihrer Kernaussagen anl\u00e4sslich des Kreisjubil\u00e4ums ist :<\/p>\n<p><strong>\u201e200 Jahre Kreis Olpe bieten Anlass zur R\u00fcckschau. Sie bieten aber auch Anlass,<br \/>\ndie Gegenwart zu feiern und optimistisch in die Zukunft zu blicken.\u201c<\/strong><\/p>\n<p>Zu den unserer Meinung nach v\u00f6llig \u00fcberh\u00f6hten\u00a0 Kosten f\u00fcr die Feierlichkeiten hat unsere Fraktion bereits mehrfach Stellung genommen und m\u00f6chte dieses zumindest im Jubil\u00e4umsjahr nicht weiter ausf\u00fchren.<\/p>\n<p>Den optimistischen Blick in die Zukunft des Kreises Olpe teilen wir jedoch mit Ihnen !<br \/>\nUnd das aus folgenden Gr\u00fcnden :<\/p>\n<ol>\n<li>Breitbandausbau<br \/>\nDurch die gute Arbeit der Kreisverwaltung bei der Erstellung der F\u00f6rderantr\u00e4ge<br \/>\nund den Kooperationsvereinbarungen mit den St\u00e4dten und Gemeinden k\u00f6nnen nach Abschluss 95% der Anschl\u00fcsse im Projektgebiet mit 50Mbit versorgt werden.<\/li>\n<li>F\u00f6rderschulen \/ Inklusion<br \/>\nDie UWG steht geschlossen hinter den Bem\u00fchungen des Landrates, alles zu unternehmen, um die hervorragend aufgestellte F\u00f6rderschullandschaft im Kreis Olpe<br \/>\nzu erhalten. Das Ausbluten der Schulen, durch die bereits von unserer Fraktion im Jahr 2011 gemachten Bef\u00fcrchtungen hinsichtlich der schulischen Inklusion werden durch neue Mindestgr\u00f6\u00dfen und Klassenfrequenzwerte erh\u00f6ht und nun auch von der<br \/>\nCDU erkannt und hoffentlich verhindert.<\/li>\n<li>Kreisstra\u00dfen<br \/>\nWie man dem Focus am 30.01.2017 entnehmen konnte, sind die Kreisstra\u00dfen im Kreis Olpe Spitze und bilden mit 3 Millionen \u20ac wiederum einen Schwerpunkt der Investitionen im diesj\u00e4hrigen Produktplan.<\/li>\n<li>Sicherheit<br \/>\nWenn man der Kriminalit\u00e4tsstatistik glauben darf, belegt die Kreispolizei bei der Aufkl\u00e4rungsquote den 1. Platz im Land NRW.<\/li>\n<li>Medizinische Versorgung<br \/>\nDer von der UWG im Jahr 2012 eingebrachte Antrag auf Einf\u00fchrung eines Medizin-stipendiums wurde hier im Hause abgelehnt und h\u00e4tte sicherlich bereits heute erste Verbesserungen bei der medizinischen Versorgung gebracht.<br \/>\nUmso mehr werden wir die Bem\u00fchungen unterst\u00fctzen, dass an der Universit\u00e4t Siegen\u00a0 ein medizinisches Studium m\u00f6glich wird und damit die Gesundheitsversorgung hier im l\u00e4ndlichen Raum gesichert wird.<\/li>\n<li>Demografie<br \/>\nDie Geburtenrate des Kreises Olpe liegt im Landesvergleich auf dem 6.Platz und l\u00e4sst auf eine Verbesserung der demografischen Entwicklung hoffen.<\/li>\n<li>Regionale<br \/>\nDie Bewerbung mit der Strategie \u201edigital-nachhaltig-authentisch\u201c hat erfolgreich zum Zuschlag f\u00fcr die Regionale 2020 oder 2025 gef\u00fchrt und l\u00e4sst uns ebenfalls optimistischer in die Zukunft unseres Kreises schauen.<\/li>\n<\/ol>\n<p>Herr Landrat, meine Damen und Herren,<br \/>\nwie auch im letzten Haushaltsjahr wird die UWG-Fraktion den vorliegenden Haushalt ablehnen. Der Grund hierf\u00fcr liegt ausschlie\u00dflich bei den freiwilligen Mehrausgaben f\u00fcr das Kreisjubil\u00e4um.<\/p>\n<p>Bedanken m\u00f6chte ich mich bei Herrn M\u00fcller und den Mitarbeitern der K\u00e4mmerei f\u00fcr die Aufstellung des Haushaltes 2017 und bei Ihnen Herr Landrat, meine Damen und Herren<br \/>\nf\u00fcr Ihre Aufmerksamkeit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Haushaltsrede 2017 Meinolf Schmidt Fraktionsvorsitzender der UWG-Fraktion im Kreistag Olpe \u2013 Es gilt das gesprochene Wort \u2013 Sehr geehrter Landrat [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"cc_featured_image_caption":{"caption_text":false,"source_text":false,"source_url":false},"_links":{"self":[{"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/posts\/1771"}],"collection":[{"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/comments?post=1771"}],"version-history":[{"count":2,"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/posts\/1771\/revisions"}],"predecessor-version":[{"id":1773,"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/posts\/1771\/revisions\/1773"}],"wp:attachment":[{"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/media?parent=1771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/categories?post=1771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uwg-kreisolpe.de\/site\/wp-json\/wp\/v2\/tags?post=1771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}